{"id":90002,"date":"2018-03-12T12:14:55","date_gmt":"2018-03-12T12:14:55","guid":{"rendered":"https:\/\/staging.agrovin.com\/senza-categoria\/mannoblanc\/"},"modified":"2022-11-06T17:01:16","modified_gmt":"2022-11-06T16:01:16","slug":"mano-blanc","status":"publish","type":"product","link":"https:\/\/agrovin.com\/it\/prodotti-enologici\/polisaccaridi-e-mannoproteine\/mano-blanc\/","title":{"rendered":"MANNOBLANC"},"content":{"rendered":"<h3>CARATTERISTICHE<\/h3>\n<ul>\n<li>I lieviti inattivi sono una fonte di polisaccaridi e mannoproteine che, oltre a partecipare alla stabilit\u00e0 tartarica e proteica dei vini bianchi, contribuiscono a migliorarne la percezione organolettica. I polisaccaridi e le mannoproteine sono direttamente coinvolti nelle sensazioni di morbidezza, volume e lunghezza in bocca, mentre la loro interazione con la frazione aromatica ne aumenta la persistenza e ne impedisce la volatilizzazione precoce.<\/li>\n<li>Il tannino gallico rafforza le propriet\u00e0 stabilizzanti e antiossidanti, aumenta la complessit\u00e0 aromatica varietale dei vini bianchi e previene l&#8217;invecchiamento precoce.<\/li>\n<li>La sua applicazione attenua la presenza di tannini astringenti derivanti da macerazioni pellicolari troppo intense o con uve poco mature, nonch\u00e9 la presenza di sgradevoli derivati tiolici.<\/li>\n<\/ul>\n<h3>APPLICAZIONE<\/h3>\n<p>Produzione di vini bianchi in cui si desidera un aumento dell&#8217;intensit\u00e0 aromatica e del volume al palato. Protezione dall&#8217;evoluzione aromatica.<\/p>\n<ul>\n<li>Utilizzato fin dalle prime fasi della vinificazione, protegge gli aromi e la freschezza dei vini bianchi e aumenta la frazione mannoproteica, ottenendo vini pi\u00f9 grassi, rotondi e persistenti.<\/li>\n<li>Grazie al suo contenuto di lievito inattivo, Mannoblanc \u00e8 un eccellente nutrimento per la fermentazione, che fornisce aminoacidi, vitamine e minerali.<\/li>\n<li>Particolarmente indicato per l&#8217;elaborazione di vini bianchi con un marcato carattere varietale o quando si desidera un successivo affinamento sui lieviti. Fornisce fecce pi\u00f9 franche, meno riduttive e pi\u00f9 stabili dal punto di vista microbiologico.<\/li>\n<\/ul>\n<h3>DOSAGGIO<\/h3>\n<div class=\"page\" title=\"Pagina 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Mosto 15-35 g\/hl<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mannoblanc \u00e8 un preparato a base di lieviti inattivati e tannino gallico. Favorisce lo sviluppo dell&#8217;espressione aromatica e aumenta la struttura e il volume. Protegge i vini bianchi dall&#8217;evoluzione precoce.<\/p>\n","protected":false},"featured_media":21140,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[216],"product_tag":[424,421],"class_list":["post-90002","product","type-product","status-publish","has-post-thumbnail","product_cat-polisaccaridi-e-mannoproteine","product_tag-levadura-inactiva-it","product_tag-corteza-de-levadura-it","pa_aplicacion-fa-e-fml","pa_ecologico-autorizzato-eu","pa_ecologico-autorizzato-nop-usda","pa_estilo-de-vino-bianco","pa_estilo-de-vino-rosato","pa_vegano-vegano-it","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","virtual","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/agrovin.com\/it\/wp-json\/wp\/v2\/product\/90002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrovin.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/agrovin.com\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/agrovin.com\/it\/wp-json\/wp\/v2\/product\/90002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrovin.com\/it\/wp-json\/wp\/v2\/media\/21140"}],"wp:attachment":[{"href":"https:\/\/agrovin.com\/it\/wp-json\/wp\/v2\/media?parent=90002"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/agrovin.com\/it\/wp-json\/wp\/v2\/product_brand?post=90002"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/agrovin.com\/it\/wp-json\/wp\/v2\/product_cat?post=90002"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/agrovin.com\/it\/wp-json\/wp\/v2\/product_tag?post=90002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}