{"id":94608,"date":"2021-05-10T10:30:51","date_gmt":"2021-05-10T09:30:51","guid":{"rendered":"https:\/\/staging.agrovin.com\/tecnicas-para-corregir-la-acidez-del-vino\/"},"modified":"2024-03-12T10:51:44","modified_gmt":"2024-03-12T09:51:44","slug":"techniques-pour-corriger-lacidite-du-vin","status":"publish","type":"post","link":"https:\/\/agrovin.com\/fr\/techniques-pour-corriger-lacidite-du-vin\/","title":{"rendered":"Techniques pour corriger l&#8217;acidit\u00e9 du vin"},"content":{"rendered":"<p>L&#8217;acidit\u00e9 d&#8217;un vin est l&#8217;une des principales caract\u00e9ristiques dont il faut tenir compte lors de son \u00e9laboration. Pour tenter de r\u00e9soudre ce probl\u00e8me, des techniques sont utilis\u00e9es pour corriger l&#8217;acidit\u00e9 du vin, qui sont r\u00e9glement\u00e9es et d\u00fbment autoris\u00e9es. Pour tenter de r\u00e9soudre ce probl\u00e8me, des techniques sont utilis\u00e9es pour <strong>corriger l&#8217;acidit\u00e9 du vin<\/strong>, qui sont r\u00e9glement\u00e9es et d\u00fbment autoris\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<h2>Le r\u00f4le de l&#8217;acidit\u00e9 dans le vin<\/h2>\n<p>&nbsp;<\/p>\n<p>Le vin poss\u00e8de sa <strong>propre acidit\u00e9, d\u00e9riv\u00e9e du raisi<\/strong>n, qui r\u00e9sulte des acides suivants :<\/p>\n<ul>\n<li><strong>L&#8217;acide tartrique<\/strong>, sp\u00e9cifique au vin.<\/li>\n<li><strong>L&#8217;acide malique<\/strong> est un type d&#8217;acide fort provenant de fruits non m\u00fbrs.<\/li>\n<li><strong>L&#8217;acide citrique<\/strong>, qui apporte des saveurs fra\u00eeches et aromatiques.<\/li>\n<\/ul>\n<p>Ult\u00e9rieurement, d&#8217;autres ar\u00f4mes issus de la fermentation du raisin sont ajout\u00e9s\u00a0:<\/p>\n<ul>\n<li><strong>L&#8217;acide succinique<\/strong>, procure des sensations sal\u00e9es et am\u00e8res en bouche, de mani\u00e8re tr\u00e8s subtile.<\/li>\n<li><strong>L&#8217;acide ac\u00e9tique<\/strong>, qui provient de la fermentation ac\u00e9tique provoqu\u00e9e par certaines bact\u00e9ries.<\/li>\n<li><strong>Acide lactique<\/strong>, issu de la fermentation malolactique (bact\u00e9ries lactiques).<\/li>\n<\/ul>\n<p>Pour les vins, <strong>l&#8217;acidit\u00e9 se situe entre 4 et 7 g\/l d&#8217;acide tartrique<\/strong>, bien qu&#8217;il soit pr\u00e9f\u00e9rable de ne jamais atteindre les deux extr\u00eames.<\/p>\n<p>Dans les vins, l&#8217;acidit\u00e9 totale est la somme de tous les acides mentionn\u00e9s ci-dessus, exprim\u00e9e en <strong>acide tartrique<\/strong>.<\/p>\n<p>Ces notions \u00e9tant claires, il est n\u00e9cessaire de dire que pour avoir <strong>un bon vin, celui-ci doit avoir un bon niveau d&#8217;acidit\u00e9.<\/strong> Si cette qualit\u00e9 fait d\u00e9faut, le vin sera de faible qualit\u00e9, ce qui se traduit par un vin terne, lourd et avec un exc\u00e8s de douceur.<\/p>\n<p>&nbsp;<\/p>\n<h2>Types d&#8217;acidit\u00e9 : acidit\u00e9 volatile et acidit\u00e9 fixe<\/h2>\n<p>&nbsp;<\/p>\n<p>L&#8217;acidit\u00e9 totale d&#8217;un vin est compos\u00e9e de l&#8217;acidit\u00e9 fixe et de l&#8217;acidit\u00e9 volatile.<\/p>\n<p>L&#8217;<strong>acidit\u00e9 fixe est l&#8217;ensemble des acides naturels<\/strong> du vin que nous avons d\u00e9j\u00e0 vu plus haut (tartrique, malique, citrique, succinique et lactique).<\/p>\n<p>Le plus important d&#8217;entre eux est l&#8217;acide tartrique, c&#8217;est pourquoi l&#8217;acidit\u00e9 fixe est mesur\u00e9e en grammes d&#8217;acide tartrique par litre.<\/p>\n<p>Les acides qui composent l&#8217;acidit\u00e9 fixe permettent de <strong>pr\u00e9server les qualit\u00e9s naturelles du vin<\/strong>, ainsi que sa couleur.<\/p>\n<p>La volatilit\u00e9 des acides dans les vins est tr\u00e8s faible, ce qui est un bon signe que le vin a la qualit\u00e9 que le vigneron recherche pour sa commercialisation.<\/p>\n<p>&nbsp;<\/p>\n<h2>Corriger l&#8217;acidit\u00e9 du vin\u00a0: les techniques pour y parvenir<\/h2>\n<p>&nbsp;<\/p>\n<p>De ce qui a \u00e9t\u00e9 dit jusqu&#8217;ici, on peut d\u00e9duire qu&#8217;avec une <strong>bonne acidification<\/strong>, le vin obtenu sera \u00e9quilibr\u00e9, aura la couleur d\u00e9sir\u00e9e, sera agr\u00e9able au palais et se conservera bien dans des conditions normales.<\/p>\n<p>Toutefois, il peut \u00eatre n\u00e9cessaire de <strong>corriger l&#8217;acidit\u00e9 au moyen de certaines techniques<\/strong> parfaitement l\u00e9gales, en l&#8217;augmentant (acidification) ou en la r\u00e9duisant (d\u00e9sacidification).<\/p>\n<p>Techniques pour corriger l&#8217;acidit\u00e9 naturelle des vins\u00a0:<\/p>\n<ul>\n<li>L&#8217;ajout d&#8217;<strong>acide tartrique<\/strong> peut se faire avant, pendant et apr\u00e8s la fermentation. Il s&#8217;agit d&#8217;une proc\u00e9dure tr\u00e8s courante qui augmente l&#8217;acidit\u00e9 totale du produit.<\/li>\n<li>L&#8217;ajout d&#8217;<strong>acide citrique<\/strong>, bien que quelque peu instable, <strong>a peu d&#8217;influence sur l&#8217;acidit\u00e9 globale.<\/strong> Une quantit\u00e9 trop importante donnera un go\u00fbt amer au vin.<\/li>\n<li>L&#8217;utilisation d&#8217;<strong>acide malique<\/strong>, qui est \u00e9galement instable, donne une saveur agressive et un go\u00fbt vert au vin.<\/li>\n<li>L&#8217;<strong>acide lactique<\/strong> adoucit le vin et lui conf\u00e8re des ar\u00f4mes agr\u00e9ables sous forme de go\u00fbts laiteux.<\/li>\n<\/ul>\n<p>Comme mentionn\u00e9 ci-dessus, les vins peuvent \u00eatre d\u00e9sacidifi\u00e9s \u00e0 l&#8217;aide de certaines levures ou par la <a href=\"https:\/\/agrovin.com\/como-optimizar-la-fermentacion-malolactica-en-primavera\/\">ferm<\/a>e<a href=\"https:\/\/agrovin.com\/como-optimizar-la-fermentacion-malolactica-en-primavera\/\">ntation malolactique.<\/a> Dans les deux cas, on agit sur l&#8217;acide malique pour obtenir une <strong>baisse de l&#8217;acidit\u00e9 du produit.<\/strong><\/p>\n<p>Il existe d&#8217;autres techniques de d\u00e9sacidification chimique\u00a0:<\/p>\n<ul>\n<li>Avec du <strong>carbonate de calcium<\/strong>. Ajout\u00e9 au vin, il r\u00e9agit avec l&#8217;acide tartrique, formant du tartrate de calcium neutre, qui pr\u00e9cipite pour r\u00e9duire l&#8217;acidit\u00e9.<\/li>\n<li><strong><a href=\"https:\/\/agrovin.com\/fr\/produit\/produits-oenologiques\/acidifiant-desacidifiant\/bicarbonate-de-potassium\/\">Bicarbonate de potassium<\/a>.<\/strong> Lorsqu&#8217;il est ajout\u00e9 au vin, il r\u00e9agit avec l&#8217;acide tartrique, formant du bitartrate de potassium qui pr\u00e9cipite en d\u00e9sacidifiant plus efficacement que le carbonate de calcium.<\/li>\n<li><strong>Tartrate de potassium neutre.<\/strong> Une mol\u00e9cule de ce compos\u00e9 r\u00e9agit avec l&#8217;acide tartrique en pr\u00e9cipitant, ce qui r\u00e9duit l&#8217;acidit\u00e9 du vin. Ce n&#8217;est pas une m\u00e9thode tr\u00e8s utilis\u00e9e car elle <strong>n&#8217;a pas une grande capacit\u00e9 \u00e0 r\u00e9duire l&#8217;acidit\u00e9<\/strong> du produit.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3><strong>Le r\u00f4le du potassium dans l&#8217;acidit\u00e9 du vin<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>L&#8217;ion potassium se trouve dans les 60 premiers centim\u00e8tres de la strate de la vigne, \u00e9tant absorb\u00e9 par les racines les plus superficielles de la plante. Les ann\u00e9es o\u00f9 les pr\u00e9cipitations sont normales ou \u00e9lev\u00e9es, <strong>les racines n&#8217;ont pas besoin d&#8217;aller chercher l&#8217;eau plus profond\u00e9ment<\/strong>, ce qui permet une plus grande absorption de K. D&#8217;autres facteurs, tels que la fertilisation, la vari\u00e9t\u00e9, le porte-greffe ou la quantit\u00e9 d&#8217;acide abscissique, influenceront les quantit\u00e9s finales de potassium dans la baie, qui seront r\u00e9parties de mani\u00e8re diff\u00e9rente entre la peau, la pulpe et la graine. Le K+ pr\u00e9sent dans la baie se trouve principalement dans la peau et dans le p\u00e9doncule, c&#8217;est pourquoi une partie tr\u00e8s importante du K+ est c\u00e9d\u00e9e lors des mac\u00e9rations.<\/p>\n<p>Les vins rouges ont des concentrations en potassium plus \u00e9lev\u00e9es d\u00fb \u00e0 leur contact avec les peaux, ainsi que ceux \u00e9labor\u00e9s avec la technique de la mac\u00e9ration carbonique <strong>en raison du contact de la rafle avec le mo\u00fbt<\/strong>, ce qui peut augmenter la quantit\u00e9 de K de 100\u00a0mg\/l. Le pH d&#8217;un vin est directement li\u00e9 \u00e0 la quantit\u00e9 de K qu&#8217;il contient.<\/p>\n<p>L&#8217;obtention de mo\u00fbts moins riches en potassium d\u00e9pend de plusieurs pratiques\u00a0:<\/p>\n<ul>\n<li><strong>Choix du sol de culture le plus appropri\u00e9.<\/strong>\u00a0Avec de faibles quantit\u00e9s de K et de faibles besoins en engrais.<\/li>\n<li><strong>Choix de vari\u00e9t\u00e9s et de porte-greffes <\/strong>ayant une faible capacit\u00e9 d&#8217;absorption de K.<\/li>\n<li><strong>Techniques culturales<\/strong> (contr\u00f4le de l&#8217;irrigation, chargement, taille&#8230;).<\/li>\n<li><strong>Mac\u00e9rations plus courtes.<\/strong><\/li>\n<li><strong>Pressage doux.<\/strong><\/li>\n<li><strong>\u00c9limination des cations <\/strong>\u00e0 travers le syst\u00e8me Free K+.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Solutions d&#8217;Agrovin pour corriger l&#8217;acidit\u00e9 du vin<\/h2>\n<p>&nbsp;<\/p>\n<p>Agrovin fournit des proc\u00e9dures d&#8217;acidification et de stabilisation des vins au moyen de r\u00e9sines \u00e9changeuses de cations qui ne r\u00e9duisent pas la qualit\u00e9 du produit.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-75676 alignright\" src=\"https:\/\/agrovin.com\/wp-content\/uploads\/2022\/03\/FreeK-1024x791-1.webp\" alt=\"\" width=\"324\" height=\"250\" title=\"\" srcset=\"https:\/\/agrovin.com\/wp-content\/uploads\/2022\/03\/FreeK-1024x791-1.webp 324w, https:\/\/agrovin.com\/wp-content\/uploads\/2022\/03\/FreeK-1024x791-1-300x231.webp 300w, https:\/\/agrovin.com\/wp-content\/uploads\/2022\/03\/FreeK-1024x791-1-270x208.webp 270w\" sizes=\"(max-width: 324px) 100vw, 324px\" \/><\/p>\n<p>Le <a href=\"https:\/\/agrovin.com\/fr\/technology\/maq-freek\/\"><strong>syst\u00e8me Free K<\/strong><\/a> implique\u00a0:<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&#8211; L&#8217;\u00e9limination des cations potassium (K) et calcium (Ca)<\/strong> qui donne lieu \u00e0 la fissuration tartrique.<\/p>\n<p><strong>&#8211; L\u2019\u00e9limination des cations fer (Fe) et cuivre (Cu)<\/strong>, qui sont responsables des ruptures ferriques et cupriques et jouent \u00e9galement le r\u00f4le de catalyseurs dans les oxydations.<\/p>\n<p>&#8211; Il r\u00e9alise le <strong>transfert de protons (H+)<\/strong> pour provoquer une augmentation de l&#8217;acidit\u00e9 totale et diminuer le pH.<\/p>\n<p>&nbsp;<\/p>\n<p>Comme nous l&#8217;avons vu, l&#8217;acidit\u00e9 des mo\u00fbts et des vins est n\u00e9cessaire et <strong>des protocoles l\u00e9gaux doivent \u00eatre \u00e9tablis<\/strong> si elle n&#8217;est pas obtenue naturellement.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La acidez de un vino es una de las caracter\u00edsticas principales que conviene cuidar cuando este se elabora. Durante la cosecha a veces intervienen factores que pueden dar al final con un caldo que no tenga la calidad adecuada. Para intentar solucionar este problema se emplean t\u00e9cnicas para corregir la acidez del vino que est\u00e1n reguladas y debidamente autorizadas.<\/p>\n","protected":false},"author":359,"featured_media":50163,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[2061,3083],"tags":[],"class_list":["post-94608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-solutions-oenologiques","category-technology-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/agrovin.com\/fr\/wp-json\/wp\/v2\/posts\/94608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agrovin.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agrovin.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agrovin.com\/fr\/wp-json\/wp\/v2\/users\/359"}],"replies":[{"embeddable":true,"href":"https:\/\/agrovin.com\/fr\/wp-json\/wp\/v2\/comments?post=94608"}],"version-history":[{"count":0,"href":"https:\/\/agrovin.com\/fr\/wp-json\/wp\/v2\/posts\/94608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agrovin.com\/fr\/wp-json\/wp\/v2\/media\/50163"}],"wp:attachment":[{"href":"https:\/\/agrovin.com\/fr\/wp-json\/wp\/v2\/media?parent=94608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agrovin.com\/fr\/wp-json\/wp\/v2\/categories?post=94608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agrovin.com\/fr\/wp-json\/wp\/v2\/tags?post=94608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}